{"id":45193,"date":"2025-11-11T09:47:57","date_gmt":"2025-11-11T01:47:57","guid":{"rendered":"https:\/\/chonghua.com.ph\/?p=45193"},"modified":"2025-11-11T09:54:05","modified_gmt":"2025-11-11T01:54:05","slug":"chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists","status":"publish","type":"post","link":"https:\/\/chonghua.com.ph\/zh\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/","title":{"rendered":"\u5d07\u534e\u533b\u9662\u548c\u5d07\u534e\u533b\u7597\u5546\u57ce\u56e0\u5176\u5728\u533b\u7597\u6280\u672f\u4eba\u5458\u4e13\u4e1a\u53d1\u5c55\u65b9\u9762\u7684\u8d21\u732e\u800c\u83b7\u5f97\u8ba4\u53ef"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"45193\" class=\"elementor elementor-45193\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71b240f e-flex e-con-boxed e-con e-parent\" data-id=\"71b240f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d785a6b elementor-widget elementor-widget-text-editor\" data-id=\"d785a6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u83f2\u5f8b\u5bbe\u533b\u5b66\u6280\u5e08\u534f\u4f1a\uff08PAMET\uff09\u5bbf\u52a1\u5206\u4f1a\u8868\u5f70\u4e86\u5d07\u534e\u96c6\u56e2\u65d7\u4e0b\u7684\u4e09\u5bb6\u673a\u6784\uff0c\u4ee5\u8868\u5f70\u5b83\u4eec\u5728\u533b\u5b66\u6280\u5e08\u7684\u4e13\u4e1a\u53d1\u5c55\u3001\u56e2\u7ed3\u548c\u5353\u8d8a\u65b9\u9762\u505a\u51fa\u7684\u6770\u51fa\u8d21\u732e\u3002<br \/><br \/>2025 \u5e74 10 \u6708 27 \u65e5\uff0c\u5728\u5bbf\u52a1\u5e02\u5357\u8def\u5730\u4ea7 NUSTAR \u5bbf\u52a1\u5927\u5bb4\u4f1a\u5385\u4e3e\u884c\u7684 PAMET \u5bbf\u52a1\u9881\u5956\u665a\u4f1a\u4e0a\uff0c\u5bbf\u52a1\u5d07\u534e\u533b\u9662\u3001\u66fc\u8fbe\u7ef4\u5d07\u534e\u533b\u9662\u548c\u5d07\u534e\u533b\u7597\u4e2d\u5fc3\u5206\u522b\u8363\u83b7\u6770\u51fa\u4f1a\u5458\u5021\u5bfc\u5353\u8d8a\u5956\u3002<br \/><br \/>\u8fd9\u4e00\u8ba4\u53ef\u51f8\u663e\u4e86\u5d07\u534e\u5927\u5b66\u81f4\u529b\u4e8e\u5728\u533b\u5b66\u6280\u672f\u9886\u57df\u4fc3\u8fdb\u4e13\u4e1a\u6210\u957f\u3001\u5408\u4f5c\u548c\u6301\u7eed\u5b66\u4e60\u7684\u51b3\u5fc3\u3002<br \/><br \/>PAMET Cebu \u8d5e\u626c\u5d07\u534e\u533b\u9662\u548c\u533b\u7597\u4e2d\u5fc3\u575a\u5b9a\u4e0d\u79fb\u5730\u5021\u5bfc\u3001\u81f4\u529b\u4e8e\u5353\u8d8a\uff0c\u5e76\u4e3a\u5bbf\u52a1\u533b\u7597\u6280\u672f\u754c\u7684\u8fdb\u6b65\u505a\u51fa\u4e86\u8d21\u732e\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09c651a e-flex e-con-boxed e-con e-parent\" data-id=\"09c651a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efbfba4 elementor-widget elementor-widget-gallery\" data-id=\"efbfba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:2,&quot;aspect_ratio&quot;:&quot;16:9&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Lab-Awards-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"efbfba4\" data-elementor-lightbox-title=\"Lab Awards (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyMDQsInVybCI6Imh0dHBzOlwvXC9jaG9uZ2h1YS5jb20ucGhcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzExXC9MYWItQXdhcmRzLTQuanBnIiwic2xpZGVzaG93IjoiZWZiZmJhNCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Lab-Awards-4-300x169.jpg\" data-width=\"300\" data-height=\"169\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Lab-Awards-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"efbfba4\" data-elementor-lightbox-title=\"Lab Awards (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyMDIsInVybCI6Imh0dHBzOlwvXC9jaG9uZ2h1YS5jb20ucGhcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzExXC9MYWItQXdhcmRzLTIuanBnIiwic2xpZGVzaG93IjoiZWZiZmJhNCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Lab-Awards-2-300x169.jpg\" data-width=\"300\" data-height=\"169\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Lab-Awards-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"efbfba4\" data-elementor-lightbox-title=\"Lab Awards (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyMDMsInVybCI6Imh0dHBzOlwvXC9jaG9uZ2h1YS5jb20ucGhcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzExXC9MYWItQXdhcmRzLTMuanBnIiwic2xpZGVzaG93IjoiZWZiZmJhNCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Lab-Awards-3-300x169.jpg\" data-width=\"300\" data-height=\"169\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Lab-Awards.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"efbfba4\" data-elementor-lightbox-title=\"Lab Awards\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUyMDUsInVybCI6Imh0dHBzOlwvXC9jaG9uZ2h1YS5jb20ucGhcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzExXC9MYWItQXdhcmRzLmpwZyIsInNsaWRlc2hvdyI6ImVmYmZiYTQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Lab-Awards-300x169.jpg\" data-width=\"300\" data-height=\"169\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u83f2\u5f8b\u5bbe\u533b\u5b66\u6280\u5e08\u534f\u4f1a\uff08PAMET\uff09\u5bbf\u52a1\u5206\u4f1a\u8868\u5f70\u4e86\u5d07\u534e\u96c6\u56e2\u65d7\u4e0b\u7684\u4e09\u5bb6\u673a\u6784\uff0c\u4ee5\u8868\u5f70\u5b83\u4eec\u5728\u533b\u5b66\u6280\u5e08\u7684\u4e13\u4e1a\u53d1\u5c55\u3001\u56e2\u7ed3\u548c\u5353\u8d8a\u65b9\u9762\u505a\u51fa\u7684\u6770\u51fa\u8d21\u732e\u3002<\/p>","protected":false},"author":3,"featured_media":45194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-45193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-announcement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists - Chong Hua Hospital - Official Website<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chonghua.com.ph\/zh\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists - Chong Hua Hospital - Official Website\" \/>\n<meta property=\"og:description\" content=\"The Philippine Association of Medical Technologists, Inc. (PAMET) Cebu recognized three institutions under the Chong Hua group for their outstanding commitment to professional development, unity, and excellence among medical technologists.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chonghua.com.ph\/zh\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/\" \/>\n<meta property=\"og:site_name\" content=\"Chong Hua Hospital - Official Website\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T01:47:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T01:54:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chong Hua Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chong Hua Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/\"},\"author\":{\"name\":\"Chong Hua Marketing\",\"@id\":\"https:\/\/chonghua.com.ph\/#\/schema\/person\/d5e687aafae4ba70f381a1bef19259cb\"},\"headline\":\"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists\",\"datePublished\":\"2025-11-11T01:47:57+00:00\",\"dateModified\":\"2025-11-11T01:54:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/\"},\"wordCount\":138,\"image\":{\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg\",\"articleSection\":[\"Announcement\"],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/\",\"url\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/\",\"name\":\"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists - Chong Hua Hospital - Official Website\",\"isPartOf\":{\"@id\":\"https:\/\/chonghua.com.ph\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg\",\"datePublished\":\"2025-11-11T01:47:57+00:00\",\"dateModified\":\"2025-11-11T01:54:05+00:00\",\"author\":{\"@id\":\"https:\/\/chonghua.com.ph\/#\/schema\/person\/d5e687aafae4ba70f381a1bef19259cb\"},\"breadcrumb\":{\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#primaryimage\",\"url\":\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg\",\"contentUrl\":\"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg\",\"width\":1024,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/chonghua.com.ph\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chonghua.com.ph\/#website\",\"url\":\"https:\/\/chonghua.com.ph\/\",\"name\":\"Chong Hua Hospital - Official Website\",\"description\":\"Healing with Passion.  Caring with Compassion.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chonghua.com.ph\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/chonghua.com.ph\/#\/schema\/person\/d5e687aafae4ba70f381a1bef19259cb\",\"name\":\"Chong Hua Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/chonghua.com.ph\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ff8a4e8a5dd6f8abc468b232db2da8f7054f7743839bda1a47b8863c4da765f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ff8a4e8a5dd6f8abc468b232db2da8f7054f7743839bda1a47b8863c4da765f?s=96&d=mm&r=g\",\"caption\":\"Chong Hua Marketing\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists - Chong Hua Hospital - Official Website","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chonghua.com.ph\/zh\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/","og_locale":"zh_CN","og_type":"article","og_title":"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists - Chong Hua Hospital - Official Website","og_description":"The Philippine Association of Medical Technologists, Inc. (PAMET) Cebu recognized three institutions under the Chong Hua group for their outstanding commitment to professional development, unity, and excellence among medical technologists.","og_url":"https:\/\/chonghua.com.ph\/zh\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/","og_site_name":"Chong Hua Hospital - Official Website","article_published_time":"2025-11-11T01:47:57+00:00","article_modified_time":"2025-11-11T01:54:05+00:00","og_image":[{"width":1024,"height":675,"url":"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg","type":"image\/jpeg"}],"author":"Chong Hua Marketing","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"Chong Hua Marketing","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#article","isPartOf":{"@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/"},"author":{"name":"Chong Hua Marketing","@id":"https:\/\/chonghua.com.ph\/#\/schema\/person\/d5e687aafae4ba70f381a1bef19259cb"},"headline":"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists","datePublished":"2025-11-11T01:47:57+00:00","dateModified":"2025-11-11T01:54:05+00:00","mainEntityOfPage":{"@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/"},"wordCount":138,"image":{"@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#primaryimage"},"thumbnailUrl":"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg","articleSection":["Announcement"],"inLanguage":"zh-Hans"},{"@type":"WebPage","@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/","url":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/","name":"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists - Chong Hua Hospital - Official Website","isPartOf":{"@id":"https:\/\/chonghua.com.ph\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#primaryimage"},"image":{"@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#primaryimage"},"thumbnailUrl":"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg","datePublished":"2025-11-11T01:47:57+00:00","dateModified":"2025-11-11T01:54:05+00:00","author":{"@id":"https:\/\/chonghua.com.ph\/#\/schema\/person\/d5e687aafae4ba70f381a1bef19259cb"},"breadcrumb":{"@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#primaryimage","url":"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg","contentUrl":"https:\/\/chonghua.com.ph\/wp-content\/uploads\/2025\/11\/Laboratory-Excellence-Award.jpg","width":1024,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/chonghua.com.ph\/announcement\/chong-hua-hospitals-and-chong-hua-medical-mall-recognized-for-the-professional-development-of-medical-technologists\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chonghua.com.ph\/"},{"@type":"ListItem","position":2,"name":"Chong Hua Hospitals and Chong Hua Medical Mall Recognized for the Professional Development of Medical Technologists"}]},{"@type":"WebSite","@id":"https:\/\/chonghua.com.ph\/#website","url":"https:\/\/chonghua.com.ph\/","name":"Chong Hua Hospital - Official Website","description":"Healing with Passion.  Caring with Compassion.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chonghua.com.ph\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Person","@id":"https:\/\/chonghua.com.ph\/#\/schema\/person\/d5e687aafae4ba70f381a1bef19259cb","name":"Chong Hua Marketing","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/chonghua.com.ph\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3ff8a4e8a5dd6f8abc468b232db2da8f7054f7743839bda1a47b8863c4da765f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ff8a4e8a5dd6f8abc468b232db2da8f7054f7743839bda1a47b8863c4da765f?s=96&d=mm&r=g","caption":"Chong Hua Marketing"}}]}},"_links":{"self":[{"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/posts\/45193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/comments?post=45193"}],"version-history":[{"count":9,"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/posts\/45193\/revisions"}],"predecessor-version":[{"id":45211,"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/posts\/45193\/revisions\/45211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/media\/45194"}],"wp:attachment":[{"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/media?parent=45193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/categories?post=45193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chonghua.com.ph\/zh\/wp-json\/wp\/v2\/tags?post=45193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}